{"id":5356,"date":"2022-03-29T16:55:47","date_gmt":"2022-03-29T14:55:47","guid":{"rendered":"https:\/\/spa.sisonke-design.com\/widerrufsbelehrung\/"},"modified":"2022-07-26T21:04:59","modified_gmt":"2022-07-26T19:04:59","slug":"right-to-withdraw","status":"publish","type":"page","link":"https:\/\/shofah.at\/en\/right-to-withdraw\/","title":{"rendered":"Right to withdraw"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; header_font=&#8221;|300|||||||&#8221; header_text_color=&#8221;#FFED00&#8243; header_line_height=&#8221;1.4em&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#FFED00&#8243; header_2_line_height=&#8221;1.2em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Right to withdraw<\/h1>\n<p>&nbsp;<\/p>\n<p>Verbrauchern steht ein Widerrufsrecht nach folgender Ma\u00dfgabe zu, wobei Verbraucher jede nat\u00fcrliche Person ist, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen:<\/p>\n<p>&nbsp;<\/p>\n<h2>1. Widerrufsrecht<\/h2>\n<p><strong>1.1<\/strong> Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden Ihren Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die letzte Ware in Besitz genommen haben bzw. hat.<br \/>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns, (Shofah Spa, S\u00e4ulengasse 13,1090 Wien, Email: office@shofah.at, Tel.: 01 317 65 64) mittels einer eindeutigen Erkl\u00e4rung (z. B. ein mit der Post versandter Brief oder per Email) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular (siehe Punkt 4.)verwenden, das jedoch nicht vorgeschrieben ist. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><strong>1.2<\/strong> Wenn Sie den Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<br \/>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden. Sie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren. Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p><strong>1.3<\/strong> Nutzer unserer Webseite k\u00f6nnen von ihrem Widerrufsrecht Gebrauch machen und der Verarbeitung ihrer personenbezogenen Daten zu jeder Zeit widersprechen. Hierf\u00fcr schreiben Sie bitte ein kurzes formloses Email an office@shofah.at .<\/p>\n<p>&nbsp;<\/p>\n<h2>2. Ausschluss bzw. vorzeitiges Erl\u00f6schen des Widerrufsrechts<\/h2>\n<p>Das Widerrufsrecht erlischt vorzeitig bei Vertr\u00e4gen zur Lieferung versiegelter Waren, die aus Gr\u00fcnden des Gesundheitsschutzes oder der Hygiene nicht zur R\u00fcckgabe geeignet sind, wenn ihre Versiegelung nach der Lieferung entfernt wurde.<br \/>Das Widerrufsrecht gilt nicht f\u00fcr Verbraucher, die zum Zeitpunkt des Vertragsschlusses keinem Mitgliedstaat der Europ\u00e4ischen Union angeh\u00f6ren und deren alleiniger Wohnsitz und Lieferadresse zum Zeitpunkt des Vertragsschlusses au\u00dferhalb der Europ\u00e4ischen Union liegen.<\/p>\n<p>&nbsp;<\/p>\n<h2>3. Allgemeine Hinweise<\/h2>\n<p><strong>3.1<\/strong> Bitte vermeiden Sie Besch\u00e4digungen und Verunreinigungen der Ware. Senden Sie die Ware bitte in Originalverpackung mit s\u00e4mtlichem Zubeh\u00f6r und mit allen Verpackungsbestandteilen an uns zur\u00fcck. Verwenden Sie ggf. eine sch\u00fctzende Umverpackung. Wenn Sie die Originalverpackung nicht mehr besitzen, sorgen Sie bitte mit einer geeigneten Verpackung f\u00fcr einen ausreichenden Schutz vor Transportsch\u00e4den.<\/p>\n<p><strong>3.2<\/strong> Senden Sie die Ware bitte nicht unfrei an uns zur\u00fcck.<\/p>\n<p><strong>3.3<\/strong> Beachten Sie, dass die vorgenannten Ziffern 3.1-3.2 nicht Voraussetzung f\u00fcr die wirksame Aus\u00fcbung des Widerrufsrechts sind.<\/p>\n<p>&nbsp;<\/p>\n<h2>4. Muster-Widerrufsformular<\/h2>\n<p>Wenn Sie den Vertrag widerrufen wollen, dann f\u00fcllen Sie bitte dieses Formular aus und senden es zur\u00fcck.<\/p>\n<p>Postalisch an<br \/>Shofah Spa<br \/>S\u00e4ulengasse 13<br \/>1090 Wien<br \/>\u00d6sterreich<\/p>\n<p>per Email an<br \/>office@shofah.at<\/p>\n<p>Hiermit widerrufe(n) ich\/wir (*) den von mir\/uns (*) abgeschlossenen Vertrag \u00fcber den Kauf der folgenden Waren (*)<\/p>\n<p>_______________________________________________________<\/p>\n<p>_______________________________________________________<\/p>\n<p>Bestellt am (*) ____________ \/ erhalten am (*) __________________<\/p>\n<p>________________________________________________________<br \/>Name des\/der Verbraucher(s)<\/p>\n<p>________________________________________________________<br \/>Anschrift des\/der Verbraucher(s)<\/p>\n<p>________________________________________________________<br \/>Unterschrift des\/der Verbraucher(s) (nur bei Mitteilung auf Papier)<\/p>\n<p>_________________________<br \/>Datum<\/p>\n<p>(*) Unzutreffendes streichen<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Right to withdraw &nbsp; Verbrauchern steht ein Widerrufsrecht nach folgender Ma\u00dfgabe zu, wobei Verbraucher jede nat\u00fcrliche Person ist, die ein Rechtsgesch\u00e4ft zu Zwecken abschlie\u00dft, die \u00fcberwiegend weder ihrer gewerblichen noch ihrer selbst\u00e4ndigen beruflichen T\u00e4tigkeit zugerechnet werden k\u00f6nnen: &nbsp; 1. Widerrufsrecht 1.1 Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden Ihren Vertrag zu [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-5356","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/pages\/5356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/comments?post=5356"}],"version-history":[{"count":0,"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/pages\/5356\/revisions"}],"wp:attachment":[{"href":"https:\/\/shofah.at\/en\/wp-json\/wp\/v2\/media?parent=5356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}